{"id":1553,"date":"2020-12-05T12:02:41","date_gmt":"2020-12-05T12:02:41","guid":{"rendered":"https:\/\/imoconnectwithwash.com\/?p=1535"},"modified":"2021-03-02T16:51:50","modified_gmt":"2021-03-02T16:51:50","slug":"key-messages-on-food-hygiene","status":"publish","type":"post","link":"https:\/\/gidanmu.com\/nigerconnectwithwash\/key-messages-on-food-hygiene\/","title":{"rendered":"Key messages on food hygiene"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1553\" class=\"elementor elementor-1553\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-958e4b9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"958e4b9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd013ad\" data-id=\"cd013ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04aefbc elementor-widget elementor-widget-heading\" data-id=\"04aefbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Key messages on food hygiene<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c12f3e1 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c12f3e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-790a85a\" data-id=\"790a85a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf1e0ef elementor-widget elementor-widget-heading\" data-id=\"bf1e0ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Always wash hands before handling food including when cooking<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbb02bc animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"fbb02bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"543\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/hand-washing-768x543.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2159\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/hand-washing-768x543.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/hand-washing-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/hand-washing.jpg 936w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be03d3a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"be03d3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4a58b6 elementor-widget elementor-widget-heading\" data-id=\"b4a58b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keep food covered always while it is waiting to be eaten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66e008a animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"66e008a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"543\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/meals-768x543.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2190\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/meals-768x543.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/meals-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/meals.jpg 936w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c740ba1 elementor-widget elementor-widget-heading\" data-id=\"c740ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avoid eating food that has fallen to the ground, except it is food like fruit - that can be effectively washed<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a5cca5 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1a5cca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"543\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/fruit-768x543.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2189\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/fruit-768x543.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/fruit-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/fruit.jpg 936w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-049f5d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"049f5d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-418a74e elementor-widget elementor-widget-heading\" data-id=\"418a74e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keep the kitchen clean all the time to prevent breeding of cockroaches and mice.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-645b5c1 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"645b5c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"725\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/sweeping-1024x725.jpg\" class=\"attachment-large size-large wp-image-1769\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/sweeping-1024x725.jpg 1024w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/sweeping-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/sweeping-768x544.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/sweeping.jpg 1480w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131a5b2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"131a5b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b661bab elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b661bab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1934adc\" data-id=\"1934adc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Key messages on food hygiene Always wash hands before handling food including when cooking Keep food covered always while it is waiting to be eaten Avoid eating food that has fallen to the ground, except it is food like fruit &#8211; that can be effectively washed Keep the kitchen clean all the time to prevent [&hellip;]<\/p>\n","protected":false},"author":987,"featured_media":1590,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-utilising-safe-water"],"blocksy_meta":[],"acf":[],"jetpack_featured_media_url":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/1-3.png","_links":{"self":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/posts\/1553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/users\/987"}],"replies":[{"embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/comments?post=1553"}],"version-history":[{"count":0,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/posts\/1553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/media\/1590"}],"wp:attachment":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/media?parent=1553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/categories?post=1553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/tags?post=1553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}