{"id":1548,"date":"2020-12-05T12:09:17","date_gmt":"2020-12-05T12:09:17","guid":{"rendered":"https:\/\/imoconnectwithwash.com\/?p=1518"},"modified":"2021-03-02T11:00:07","modified_gmt":"2021-03-02T11:00:07","slug":"safe-excreta-disposal-for-households","status":"publish","type":"post","link":"https:\/\/gidanmu.com\/nigerconnectwithwash\/safe-excreta-disposal-for-households\/","title":{"rendered":"Safe excreta disposal for households"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1548\" class=\"elementor elementor-1548\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e81758c elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e81758c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e7d638\" data-id=\"3e7d638\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d76eea7 elementor-widget elementor-widget-heading\" data-id=\"d76eea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Safe excreta disposal for households<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b054ee3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b054ee3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b5a01e\" data-id=\"0b5a01e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309fb6f elementor-widget elementor-widget-text-editor\" data-id=\"309fb6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Toilet cleanliness is very important for you and your household. Toilet is the place where all the germs and bacteria start their attacks on the human body. That is the reason why the toilets need to be clean all the time.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6805588 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6805588\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c46459\" data-id=\"9c46459\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-737b81f elementor-widget elementor-widget-heading\" data-id=\"737b81f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cover your toilet after use<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f4b89 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a4f4b89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"543\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/cover-768x543.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2161\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/cover-768x543.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/cover-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/cover.jpg 936w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef3349 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2ef3349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e119701 elementor-widget elementor-widget-heading\" data-id=\"e119701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Flush your toilet after use when using Water closet to avoid infection<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8fdd83 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e8fdd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"543\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/flush-768x543.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2163\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/flush-768x543.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/flush-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/flush.jpg 936w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9a77ac elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f9a77ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4cc076 elementor-widget elementor-widget-heading\" data-id=\"f4cc076\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Make use of anal cleansing materials or water after using the toilet\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0139eae animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0139eae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"543\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/tissue-and-water-768x543.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2164\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/tissue-and-water-768x543.jpg 768w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/tissue-and-water-300x212.jpg 300w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/tissue-and-water.jpg 936w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2f6ec9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b2f6ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ece073 elementor-widget elementor-widget-heading\" data-id=\"5ece073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keep your toilets surroundings clean always<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e7762a animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2e7762a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/imoconnectwithwash.com\/wp-content\/uploads\/sites\/6\/2020\/12\/5-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d14d4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"24d14d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d96a8ef elementor-widget elementor-widget-heading\" data-id=\"d96a8ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keep the surroundings of the septic tank clean and disinfected to avoid pests, rodents and creeping animals from breeding there.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-648b5f0 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"648b5f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"423\" src=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/1-4.png\" class=\"attachment-medium_large size-medium_large wp-image-1604\" alt=\"\" srcset=\"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/1-4.png 600w, https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/1-4-300x212.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06d8e5d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"06d8e5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-298bf6e elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"298bf6e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c123c41\" data-id=\"c123c41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-223834e elementor-widget elementor-widget-heading\" data-id=\"223834e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Water is life, No water, No life! Be careful, save water!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Safe excreta disposal for households Toilet cleanliness is very important for you and your household. Toilet is the place where all the germs and bacteria start their attacks on the human body. That is the reason why the toilets need to be clean all the time. Cover your toilet after use Flush your toilet after [&hellip;]<\/p>\n","protected":false},"author":987,"featured_media":1968,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-utilising-safe-water"],"blocksy_meta":[],"acf":[],"jetpack_featured_media_url":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-content\/uploads\/sites\/6\/2020\/12\/admin-ajax-4.jpg","_links":{"self":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/posts\/1548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/users\/987"}],"replies":[{"embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/comments?post=1548"}],"version-history":[{"count":0,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/posts\/1548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/media\/1968"}],"wp:attachment":[{"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/media?parent=1548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/categories?post=1548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gidanmu.com\/nigerconnectwithwash\/wp-json\/wp\/v2\/tags?post=1548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}